{"id":12732,"date":"2024-02-20T16:51:09","date_gmt":"2024-02-20T16:51:09","guid":{"rendered":"https:\/\/laverdadpublica.com\/?p=12732"},"modified":"2024-02-20T16:51:09","modified_gmt":"2024-02-20T16:51:09","slug":"movimiento-ciudadano-diferente-celebra-el-triunfo-abrazador-de-dio-astacio","status":"publish","type":"post","link":"https:\/\/laverdadpublica.com\/index.php\/2024\/02\/20\/movimiento-ciudadano-diferente-celebra-el-triunfo-abrazador-de-dio-astacio\/","title":{"rendered":"Movimiento Ciudadano Diferente celebra el triunfo abrazador de Dio Astacio."},"content":{"rendered":"<p><img decoding=\"async\" class=\"size-medium wp-image-12733 alignright lazyload\" data-src=\"https:\/\/laverdadpublica.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-20-at-12.42.12-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" data-srcset=\"https:\/\/laverdadpublica.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-20-at-12.42.12-300x200.jpeg 300w, https:\/\/laverdadpublica.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-20-at-12.42.12-1024x683.jpeg 1024w, https:\/\/laverdadpublica.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-20-at-12.42.12-768x512.jpeg 768w, https:\/\/laverdadpublica.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-20-at-12.42.12-1536x1024.jpeg 1536w, https:\/\/laverdadpublica.com\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-20-at-12.42.12-2048x1365.jpeg 2048w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\" \/><\/p>\n<p style=\"text-align: justify;\">El licenciado Bonny Mart\u00ednez, presidente del Movimiento Ciudadano Diferente, agradeci\u00f3 este lunes a cada uno de sus integrantes que con su arduo esfuerzo, lograron la victoria del hoy electo a la alcald\u00eda de Santo Domingo.<\/p>\n<blockquote><p><em>\u00abReuniones por aqu\u00ed, reuniones por all\u00e1, llenado de formularios y su presencia activa en los mano a mano junto al candidato, fueron parte de las acciones efectuadas por ustedes, que empujaron el triunfo de nuestro candidato\u00bb<\/em>, destac\u00f3 Mart\u00ednez.<\/p><\/blockquote>\n<p style=\"text-align: justify;\">De igual manera, reconoci\u00f3 que el Movimiento Ciudadano Diferente no ser\u00eda posible sino fuera gracias a la colaboraci\u00f3n con su tiempo, esfuerzo y talento de los m\u00e1s de 300 l\u00edderes y coordinadores del municipio Santo Domingo Este que se sumaron a esa iniciativa.<\/p>\n<p style=\"text-align: justify;\">\u00abCiudadano Diferente no es solo Bonny Mart\u00ednez, Ciudadano Diferente es cada hombre y mujer que crey\u00f3 y apoy\u00f3 est\u00e1 iniciativa\u00bb.<\/p>\n<p style=\"text-align: justify;\">Mart\u00ednez, como l\u00edder del movimiento agradeci\u00f3 especialmente a Ronny Aquino, coordinador general de la circunscripcion 1, Victor Mateo en Los Minas Norte, Jos\u00e9 Robles, de La Ure\u00f1a; Jiancarlos Feliz, coordinador de Hainamosa; y a los<br \/>\nvicepresidentes Abigain Berroa, Robert Santos y Vladimir Alc\u00e1ntara, por convertirse en su mano derecha de lo que hoy es Ciudadano Diferente.<\/p>\n<p style=\"text-align: justify;\">Finalmente, Bonny Mart\u00ednez reafirm\u00f3 su compromiso de trabajar con su movimiento para, junto a la gesti\u00f3n de Dio Astacio, hacer de Santo Domingo Este una ciudad prospera y llena de oportunidades para todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El licenciado Bonny Mart\u00ednez, presidente del Movimiento Ciudadano Diferente, agradeci\u00f3 este lunes a cada uno<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-12732","post","type-post","status-publish","format-standard","hentry","category-politicas"],"_links":{"self":[{"href":"https:\/\/laverdadpublica.com\/index.php\/wp-json\/wp\/v2\/posts\/12732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laverdadpublica.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laverdadpublica.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laverdadpublica.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/laverdadpublica.com\/index.php\/wp-json\/wp\/v2\/comments?post=12732"}],"version-history":[{"count":1,"href":"https:\/\/laverdadpublica.com\/index.php\/wp-json\/wp\/v2\/posts\/12732\/revisions"}],"predecessor-version":[{"id":12734,"href":"https:\/\/laverdadpublica.com\/index.php\/wp-json\/wp\/v2\/posts\/12732\/revisions\/12734"}],"wp:attachment":[{"href":"https:\/\/laverdadpublica.com\/index.php\/wp-json\/wp\/v2\/media?parent=12732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laverdadpublica.com\/index.php\/wp-json\/wp\/v2\/categories?post=12732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laverdadpublica.com\/index.php\/wp-json\/wp\/v2\/tags?post=12732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}